{"id":71,"count":1,"description":"","link":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/","name":"R\u00e9visions Bac","slug":"revision_bac","taxonomy":"category","parent":6,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre<\/title>\n<meta name=\"description\" content=\"Bienvenue sur le site de Sciences de la Vie et de la Terre %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre\" \/>\n<meta property=\"og:description\" content=\"Bienvenue sur le site de Sciences de la Vie et de la Terre %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienvenue sur le site de Sciences de la Vie et de la Terre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/\",\"url\":\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/\",\"name\":\"Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre\",\"isPartOf\":{\"@id\":\"https:\/\/svt-dalaine.fr\/svt\/#website\"},\"description\":\"Bienvenue sur le site de Sciences de la Vie et de la Terre %\",\"breadcrumb\":{\"@id\":\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/svt-dalaine.fr\/svt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terminale\",\"item\":\"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9visions Bac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/svt-dalaine.fr\/svt\/#website\",\"url\":\"https:\/\/svt-dalaine.fr\/svt\/\",\"name\":\"Bienvenue sur le site de Sciences de la Vie et de la Terre\",\"description\":\"Ressources en SVT de St\u00e9phanie Dalaine, professeure agr\u00e9g\u00e9e exer\u00e7ant en BCPST1 ENCPB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/svt-dalaine.fr\/svt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre","description":"Bienvenue sur le site de Sciences de la Vie et de la Terre %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre","og_description":"Bienvenue sur le site de Sciences de la Vie et de la Terre %","og_url":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/","og_site_name":"Bienvenue sur le site de Sciences de la Vie et de la Terre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/","url":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/","name":"Archives des R\u00e9visions Bac - Bienvenue sur le site de Sciences de la Vie et de la Terre","isPartOf":{"@id":"https:\/\/svt-dalaine.fr\/svt\/#website"},"description":"Bienvenue sur le site de Sciences de la Vie et de la Terre %","breadcrumb":{"@id":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/revision_bac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/svt-dalaine.fr\/svt\/"},{"@type":"ListItem","position":2,"name":"Terminale","item":"https:\/\/svt-dalaine.fr\/svt\/category\/terminale\/"},{"@type":"ListItem","position":3,"name":"R\u00e9visions Bac"}]},{"@type":"WebSite","@id":"https:\/\/svt-dalaine.fr\/svt\/#website","url":"https:\/\/svt-dalaine.fr\/svt\/","name":"Bienvenue sur le site de Sciences de la Vie et de la Terre","description":"Ressources en SVT de St\u00e9phanie Dalaine, professeure agr\u00e9g\u00e9e exer\u00e7ant en BCPST1 ENCPB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svt-dalaine.fr\/svt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/categories\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/categories\/6"}],"wp:post_type":[{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/posts?categories=71"},{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/pages?categories=71"},{"href":"https:\/\/svt-dalaine.fr\/svt\/wp-json\/wp\/v2\/media?categories=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}